{"id":30352,"date":"2023-05-18T13:46:17","date_gmt":"2023-05-18T13:46:17","guid":{"rendered":"https:\/\/frontexprep.com\/corso-per-candidati-al-corpo-permanente-di-frontex\/"},"modified":"2025-04-25T16:37:20","modified_gmt":"2025-04-25T16:37:20","slug":"corso-per-candidati-al-corpo-permanente-di-frontex","status":"publish","type":"page","link":"https:\/\/frontexprep.com\/it\/","title":{"rendered":"Corso per Candidati al Corpo Permanente di Frontex"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"30352\" class=\"elementor elementor-30352 elementor-13480\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbcab9a elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"dbcab9a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85bb968\" data-id=\"85bb968\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e94a126 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e94a126\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-654c74e\" data-id=\"654c74e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbd5218 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cbd5218\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"48\" height=\"123\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/h-1-shape-01.png\" class=\"attachment-full size-full wp-image-100\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9dd2a40 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dd2a40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c10db3\" data-id=\"6c10db3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11eb0ca elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"11eb0ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-13.png\" alt=\"Hero-Shape-1\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b0395 edublink-br-tl-none elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"07b0395\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"edublink-color-secondary\">Corso<\/span> Completo <br>\nper Candidati al Corpo Permanente di Frontex<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c8b864 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7c8b864\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La tua guida online definitiva per prepararti al reclutamento di Frontex e intraprendere la carriera nel Corpo Permanente.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ef10c1 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9ef10c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questo \u00e8 un corso indipendente. Non siamo affiliati con Frontex e non garantiamo il reclutamento. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4c1de1 elementor-invisible elementor-widget elementor-widget-edublink-button\" data-id=\"d4c1de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-default edublink-button-size-custom edublink-button-icon-position-after default-style\" href=\"\/courses\/standing-corps-course\/\">Inizia<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24fccba\" data-id=\"24fccba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b75d644 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"b75d644\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-color edublink-mouse-track-item\"><span data-depth=\"3\"><span class=\"edublink-animation-widget-color\"><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c955f3 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"0c955f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-1.5\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-16.png\" alt=\"Hero-Shape-2\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f6e7c1 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"4f6e7c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-infinite-animation edublink-animation-content-type-image\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/shape-15-blue.png\" alt=\"shape-15-blue\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95606d9 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"95606d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"1.5\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-13.png\" alt=\"Hero-Shape-1\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ede4e99 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"ede4e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-color edublink-mouse-track-item\"><span data-depth=\"3\"><span class=\"edublink-animation-widget-color\"><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c792638 elementor-widget__width-auto elementor-absolute elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-html\" data-id=\"c792638\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-hm-instructor-info edublink-bg-white edublink-color-heading edublink-radius\">\n    <div class=\"instructor-wrapper\">\n        <h5 class=\"title edublink-color-heading\">5.0 \u2b50\u2b50\u2b50\u2b50\u2b50 Recensioni<\/h5>\n        <div class=\"instructor-media\">\n            <div class=\"thumb\">\n                <img decoding=\"async\" src=\"https:\/\/frontexprep.com\/author-1-1-1.png?_t=1736825915\">\n            <\/div>\n            <div class=\"content\">\n                <span class=\"edublink-color-secondary edublink-p-bold\">Carriera <br><\/span> Elevata\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5bafa8 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"d5bafa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-left&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"538\" height=\"605\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Fr-St-Crps-female.webp\" class=\"attachment-full size-full wp-image-28902\" alt=\"\" srcset=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Fr-St-Crps-female.webp 538w, https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Fr-St-Crps-female-267x300.webp 267w\" sizes=\"(max-width: 538px) 100vw, 538px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16d999e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"16d999e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-974eea0\" data-id=\"974eea0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f37279 elementor-widget elementor-widget-heading\" data-id=\"9f37279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Iscriviti alla Newsletter<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82c4c59 elementor-widget elementor-widget-heading\" data-id=\"82c4c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Webinar Gratuiti, Consigli e Suggerimenti per l\u2019Esame<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9f8df3 fluent-form-widget-step-header-yes fluent-form-widget-step-progressbar-yes fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"c9f8df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_7 ffs_default_wrap'><form data-form_id=\"7\" id=\"fluentform_7\" class=\"frm-fluent-form fluent_form_7 ff-el-form-top ff_form_instance_7_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_7_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">IT Newsletter<\/legend><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"53\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><input type='hidden' name='__fluent_form_embded_post_id' value='30352' \/><input type=\"hidden\" id=\"_fluentform_7_fluentformnonce\" name=\"_fluentform_7_fluentformnonce\" value=\"d7cf44d88f\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/30352\" \/><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div data-type=\"name-element\" data-name=\"first_name\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class='ff-el-input--content'><input type=\"text\" name=\"first_name[first_name]\" id=\"ff_7_first_name_first_name_\" class=\"ff-el-form-control\" placeholder=\"Nome\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div class='ff-el-group'><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_7_email\" class=\"ff-el-form-control\" placeholder=\"Email\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='Terms and Conditions: Accetto di ricevere le newsletter e accetto i termini nella Politica sulla privacy. Contains 1 link. Use tab navigation to review.' class='ff-el-form-check-label ff_tc_label' for=terms-n-condition_20eca192345c70d8c1b558f77e9e8032><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"terms-n-condition\" class=\"ff-el-form-check-input\" data-name=\"terms-n-condition\" id=\"terms-n-condition_20eca192345c70d8c1b558f77e9e8032\"  value='on' aria-invalid='false' aria-required=true><\/span> <div class='ff_t_c'><p>Accetto di ricevere le newsletter e accetto i termini nella <a href=\"https:\/\/frontexprep.com\/it\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Politica sulla privacy<\/a>.<\/p><\/div><\/label><\/div><\/div><div class='ff-el-group ff-text-center ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Iscrizione alla Newsletter\">Iscrizione alla Newsletter<\/button><\/div><\/fieldset><\/form><div id='fluentform_7_errors' class='ff-errors-in-stack ff_form_instance_7_1 ff-form-loading_errors ff_form_instance_7_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_7_1 = {\"id\":\"7\",\"ajaxUrl\":\"https:\\\/\\\/frontexprep.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_7_1\",\"form_id_selector\":\"fluentform_7\",\"rules\":{\"first_name[first_name]\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"first_name[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"first_name[last_name]\":{\"required\":{\"value\":false,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":true,\"message\":\"Questo campo deve contenere un indirizzo email valido\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"terms-n-condition\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}}},\"debounce_time\":300,\"file_upload_settings\":[]};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57db4c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57db4c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67acdf4\" data-id=\"67acdf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf2cfd1 elementor-invisible elementor-widget elementor-widget-edublink-heading\" data-id=\"bf2cfd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-up&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><h3 class=\"heading\">Iscriviti Ora e Inizia<\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45635a0 elementor-widget__width-inherit elementor-widget elementor-widget-edublink-button\" data-id=\"45635a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-default edublink-button-size-large edublink-button-icon-position-after default-style\" href=\"\/courses\/standing-corps-course\/\">Inizia<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-748b543 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"748b543\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c25c1d1\" data-id=\"c25c1d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34e1c92 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"34e1c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"1\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/06\/shape-36-1.png\" alt=\"About-Shape-1\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42df9c9 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"42df9c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-1\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/07\/shape-37.png\" alt=\"About-Shape-2\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea8250 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"6ea8250\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"1\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/06\/shape-02.png\" alt=\"About-Shape-3\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4f2917 elementor-widget__width-auto elementor-absolute elementor-hidden-mobile bounce-slide elementor-widget elementor-widget-html\" data-id=\"d4f2917\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-h-main-about-us edublink-bg-white edublink-radius\">\n    <div class=\"about-us-media\">\n        <div class=\"icon\">\n            <i class=\"icon-21\"><\/i>\n        <\/div>\n        <div class=\"content\">\n            <h6 class=\"edublink-color-primary edublink-p-semi-bold\">2<\/h6>\n             <span class=\"edublink-p-regular edublink-color-body\">Libri Pubblicati<\/span>\n        <\/div>\n    <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8eafd1 elementor-widget__width-auto elementor-absolute elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-video-popup\" data-id=\"f8eafd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;edublink--slide-down&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edublink-video-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-video-popup-wrapper edublink-video-popup-animation-never\"><div class=\"edublink-video-popup-content\"><a class=\"edublink-video-popup-icon\" href=\"https:\/\/youtu.be\/WkZVri9h8r8\"><i aria-hidden=\"true\" class=\"ri ri-play-fill\"><\/i><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d7db6 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"b0d7db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;edublink--slide-down&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"260\" height=\"210\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Fr-candidate-studying-260-x-210-1.png\" class=\"attachment-full size-full wp-image-28909\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd64929 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cd64929\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;edublink--slide-right&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"420\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Candidate-Studying-Fr.webp\" class=\"attachment-full size-full wp-image-28916\" alt=\"\" srcset=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Candidate-Studying-Fr.webp 370w, https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Candidate-Studying-Fr-264x300.webp 264w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ba8ffb elementor-invisible\" data-id=\"7ba8ffb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-left&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c118ba0 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"c118ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-color edublink-mouse-track-item\"><span data-depth=\"-2.3\"><span class=\"edublink-animation-widget-color\"><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8df9de9 elementor-widget elementor-widget-edublink-heading\" data-id=\"8df9de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">CHI SIAMO<\/span><h3 class=\"heading\">Reclutamento del Corpo Permanente di Frontex <mark>Corso<\/mark><\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><div class=\"sub-heading\"><p>Ti stai preparando per una carriera con Frontex, l'Agenzia Europea della Guardia di Frontiera e Costiera? Le nostre risorse didattiche complete sono progettate per aiutarti a costruire le tue conoscenze.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b85c46 edublink-font-secondary elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8b85c46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"edublink icon-20\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Corso Conducono Esperti<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"edublink icon-20\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Libro Pubblicato Incluso<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"edublink icon-20\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accesso Illimitato ai Materiali<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c621e0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c621e0c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-49c955c elementor-invisible\" data-id=\"49c955c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:50}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6a64b1 elementor-widget elementor-widget-edublink-heading\" data-id=\"f6a64b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-section-heading\"><span class=\"pre-heading\">TESTIMONIANZE<\/span><h3 class=\"heading\">Cosa Hanno Da Dire I Nostri Studenti<\/h3><div class=\"title-shape\"><i class=\"icon-19\"><\/i><\/div><div class=\"sub-heading\"><p>Scopri come il nostro corso ha aiutato i candidati aspiranti al Corpo Permanente di Frontex a migliorare la loro preparazione e ad affrontare il processo di reclutamento con maggiore fiducia.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e92f4aa elementor-widget elementor-widget-edublink-button\" data-id=\"e92f4aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-default edublink-button-size-large edublink-button-icon-position-after default-style\" href=\"\/courses\/standing-corps-course\/\">Inizia<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0ba7416\" data-id=\"0ba7416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c3b084 elementor-widget elementor-widget-edublink-testimonial\" data-id=\"9c3b084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eb-testimonial-wrapper eb-testimonial-wrapper-style-1\"><div class=\"eb-testimonial eb-testimonial-style-1 swiper swiper-container swiper-container-initialized\"><div class=\"swiper-wrapper\" data-autoplay=\"true\" data-autoplayspeed=\"0\"><div class=\"swiper-slide\"><div class=\"eb-testimonial-item elementor-repeater-item-f39b7d1\"><div class=\"eb-testimonial-grid\"><div class=\"thumbnail\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/testimonial-1.png\" class=\"testimonial-author-avatar\" alt=\"testimonial-1\"><span class=\"qoute-icon\"><i class=\"icon-26\"><\/i><\/span><\/div><div class=\"content\"><p class=\"description\">Questo corso mi ha dato la chiarezza e la fiducia di cui avevo bisogno per comprendere meglio il processo di reclutamento di Frontex.<\/p><div class=\"rating-icon\"><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><\/div><h5 class=\"title\">Giorgos Chronidis<\/h5><span class=\"subtitle\">Grecia (Tradotto)<\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"eb-testimonial-item elementor-repeater-item-76ca1dd\"><div class=\"eb-testimonial-grid\"><div class=\"thumbnail\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/testimonial-2.png\" class=\"testimonial-author-avatar\" alt=\"testimonial-2\"><span class=\"qoute-icon\"><i class=\"icon-26\"><\/i><\/span><\/div><div class=\"content\"><p class=\"description\">Grazie a questo corso, mi sono sentita ben preparata e informata. I materiali erano chiari, pratici e facili da seguire!<\/p><div class=\"rating-icon\"><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><\/div><h5 class=\"title\">Anna Kowalska<\/h5><span class=\"subtitle\">Polonia (Tradotto)<\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"eb-testimonial-item elementor-repeater-item-4015e78\"><div class=\"eb-testimonial-grid\"><div class=\"thumbnail\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/testimonial-3.png\" class=\"testimonial-author-avatar\" alt=\"testimonial-3\"><span class=\"qoute-icon\"><i class=\"icon-26\"><\/i><\/span><\/div><div class=\"content\"><p class=\"description\">La guida di Maria \u00e8 stata eccezionale! Le sue spiegazioni chiare hanno fatto una grande differenza nella mia preparazione!<\/p><div class=\"rating-icon\"><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><\/div><h5 class=\"title\">Andrei Popescu<\/h5><span class=\"subtitle\">Romania (Tradotto)<\/span><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"eb-testimonial-item elementor-repeater-item-849f7a6\"><div class=\"eb-testimonial-grid\"><div class=\"thumbnail\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/testimonial-4.png\" class=\"testimonial-author-avatar\" alt=\"testimonial-4\"><span class=\"qoute-icon\"><i class=\"icon-26\"><\/i><\/span><\/div><div class=\"content\"><p class=\"description\">Spiegazioni dettagliate, esempi pratici e utili spunti. Mi ha fatto sentire molto pi\u00f9 sicura!!!<\/p><div class=\"rating-icon\"><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><i class=\"icon-23\"><\/i><\/div><h5 class=\"title\">Giulia Rossi<\/h5><span class=\"subtitle\">Italia (Tradotto)<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8ade211 e-flex e-con-boxed e-con e-parent\" data-id=\"8ade211\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7a04672 e-flex e-con-boxed e-con e-child\" data-id=\"7a04672\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8ab65 elementor-widget elementor-widget-heading\" data-id=\"ee8ab65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comunit\u00e0 Facebook Gratuita per i Candidati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a08b8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a08b8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85d8164\" data-id=\"85d8164\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95f5f8f elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-widget elementor-widget-edublink-animation\" data-id=\"95f5f8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-12.png\" alt=\"shape-12\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d14fa elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-widget elementor-widget-edublink-animation\" data-id=\"32d14fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-06.png\" alt=\"shape-06\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca3d18b elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-widget elementor-widget-edublink-animation\" data-id=\"ca3d18b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-3\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-04-1.png\" alt=\"Hero Shape 7\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dd2d09f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd2d09f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b7b841\" data-id=\"6b7b841\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-726ac9c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"726ac9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/elementor\/thumbs\/Facebook_Logo_Primary-qzwyvd3w3wjnv62mrkj0gd62wknlc4padihvqwxxks.png\" title=\"Facebook_Logo_Primary\" alt=\"Facebook_Logo_Primary\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-04e083a\" data-id=\"04e083a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84d7be0 elementor-widget elementor-widget-heading\" data-id=\"84d7be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Unisciti alla Comunit\u00e0 Facebook Gratuita<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17cdd12 elementor-widget elementor-widget-heading\" data-id=\"17cdd12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/facebook.com\">CLICCA PER UNIRTI<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ed9a72e e-flex e-con-boxed e-con e-parent\" data-id=\"ed9a72e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c100a2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8c100a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-acaad14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"acaad14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d18fc0\" data-id=\"3d18fc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69b03a8 elementor-widget elementor-widget-heading\" data-id=\"69b03a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Corso sul Reclutamento del Corpo Permanente di Frontex<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9faa0ad elementor-widget elementor-widget-heading\" data-id=\"9faa0ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">La Tua Porta d'Ingresso a una Carriera nella Sicurezza delle Frontiere<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72b1b8c elementor-widget elementor-widget-text-editor\" data-id=\"72b1b8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sei pronto a unirti ai ranghi del Corpo Permanente di Frontex, il primo servizio uniformato di guardia di frontiera e di costa dell&#8217;UE? Il nostro <strong>Corso sul Reclutamento del Corpo Permanente di Frontex<\/strong> \u00e8 specificamente progettato per preparare i candidati a ogni fase del processo di reclutamento. Offrendo un programma ben strutturato che copre le politiche di gestione delle frontiere dell&#8217;UE, le procedure operative e le tecniche di intervista basate sulle competenze, ci assicuriamo che tu acquisisca le conoscenze e le competenze pratiche necessarie per essere ben preparato.  <\/p>\n<p>Il Corso \u00e8 guidato da esperti con profonde conoscenze del processo di reclutamento e delle operazioni di Frontex. I partecipanti traggono beneficio da esercizi pratici, studi di caso reali e apprendimento basato su scenari, fornendo loro una chiara comprensione dei compiti e delle sfide che potrebbero affrontare come parte del Corpo Permanente. Questo approccio pratico \u00e8 fondamentale per sviluppare sia la competenza che la fiducia.  <\/p>\n<p>Il nostro Corso sul Reclutamento del Corpo Permanente di Frontex si concentra su aree critiche come la valutazione del rischio, la gestione delle crisi e la cooperazione transfrontaliera. Questi argomenti sono essenziali per i candidati che mirano a navigare in ambienti operativi complessi. Inoltre, il corso sottolinea la presa di decisioni etiche e i diritti fondamentali, entrambi integrali alle responsabilit\u00e0 di un ufficiale di Frontex.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c42dd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c42dd1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-207a291\" data-id=\"207a291\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f63e13 elementor-widget elementor-widget-edublink-video-popup\" data-id=\"3f63e13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-video-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-video-popup-wrapper edublink-video-popup-animation-continious edublink-video-popup-continious-type-colored edublink-video-popup-bg-enable\" style=\"background-image: url(https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/background-pic-video.jpg)\"><div class=\"edublink-video-popup-content\"><a class=\"edublink-video-popup-icon\" href=\"https:\/\/youtu.be\/WkZVri9h8r8\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c731df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7c731df\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e5d054 elementor-invisible\" data-id=\"6e5d054\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;edublink--slide-up&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60331ae elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-widget elementor-widget-edublink-animation\" data-id=\"60331ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2.5\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/shape-15-blue.png\" alt=\"shape-15-blue\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4da55e8 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"4da55e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2.5\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-10.png\" alt=\"shape-10\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48ba1ac elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-widget elementor-widget-edublink-animation\" data-id=\"48ba1ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-02.png\" alt=\"Hero-Shape-18\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7baffe elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-mobile_extra elementor-widget elementor-widget-edublink-animation\" data-id=\"f7baffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"2\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-13.png\" alt=\"Hero-Shape-1\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe58f08 edublink-br-tl-none elementor-widget elementor-widget-heading\" data-id=\"fe58f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inizia il <span class=\"edublink-color-secondary\">Corso<\/span> <br>\nFai il primo passo verso la tua carriera in Frontex<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6af0ccc elementor-widget elementor-widget-edublink-button\" data-id=\"6af0ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edublink-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-button-widget-wrapper\"><a class=\"edublink-button-item edublink-button-style-default edublink-button-size-large edublink-button-icon-position-after default-style\" href=\"\/courses\/standing-corps-course\/\">Inizia<i class=\"icon-4\"><\/i><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ac773a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7ac773a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed3786d\" data-id=\"ed3786d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1029f41 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"1029f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-1.4\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/06\/shape-02.png\" alt=\"About-Shape-3\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba19cc0 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"ba19cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-image edublink-mouse-track-item\"><span data-depth=\"-2.3\"><img decoding=\"async\" src=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/shape-05.png\" alt=\"Hero-Shape-32\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bab2f16 elementor-widget__width-auto elementor-absolute elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-edublink-animation\" data-id=\"bab2f16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"edublink-animation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edublink-animation-widget edublink-animation-display-type-mouse-track edublink-animation-content-type-color edublink-mouse-track-item\"><span data-depth=\"2.5\"><span class=\"edublink-animation-widget-color\"><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Corso Completo per Candidati al Corpo Permanente di Frontex La tua guida online definitiva per prepararti al reclutamento di Frontex e intraprendere la carriera nel Corpo Permanente. Questo \u00e8 un corso indipendente. Non siamo affiliati con Frontex e non garantiamo il reclutamento. Inizia 5.0 \u2b50\u2b50\u2b50\u2b50\u2b50 Recensioni Carriera Elevata Iscriviti alla Newsletter Webinar Gratuiti, Consigli e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30352","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FrontexPrep &#8226; Corso per Candidati al Corpo Permanente di Frontex<\/title>\n<meta name=\"description\" content=\"Prepara per il reclutamento Frontex con il nostro corso progettato per i candidati al Corpo Permanente. Acquisisci le competenze!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frontexprep.com\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FrontexPrep &#8226; Corso per Candidati al Corpo Permanente di Frontex\" \/>\n<meta property=\"og:description\" content=\"Prepara per il reclutamento Frontex con il nostro corso progettato per i candidati al Corpo Permanente. Acquisisci le competenze!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frontexprep.com\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"FrontexPrep\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T16:37:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/h-1-shape-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"48\" \/>\n\t<meta property=\"og:image:height\" content=\"123\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/\",\"url\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/\",\"name\":\"FrontexPrep &#8226; Corso per Candidati al Corpo Permanente di Frontex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frontexprep.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/h-1-shape-01.png\",\"datePublished\":\"2023-05-18T13:46:17+00:00\",\"dateModified\":\"2025-04-25T16:37:20+00:00\",\"description\":\"Prepara per il reclutamento Frontex con il nostro corso progettato per i candidati al Corpo Permanente. Acquisisci le competenze!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frontexprep.com\\\/it\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frontexprep.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/h-1-shape-01.png\",\"contentUrl\":\"https:\\\/\\\/frontexprep.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/h-1-shape-01.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corso per Candidati al Corpo Permanente di Frontex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/\",\"name\":\"FrontexPrep\",\"description\":\"Course on Frontex Standing Corps Recruitment\",\"publisher\":{\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#organization\",\"name\":\"FrontexPrep\",\"url\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frontexprep.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Standing-Corps-prep-course-logo.png\",\"contentUrl\":\"https:\\\/\\\/frontexprep.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Standing-Corps-prep-course-logo.png\",\"width\":158,\"height\":50,\"caption\":\"FrontexPrep\"},\"image\":{\"@id\":\"https:\\\/\\\/frontexprep.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FrontexPrep &#8226; Corso per Candidati al Corpo Permanente di Frontex","description":"Prepara per il reclutamento Frontex con il nostro corso progettato per i candidati al Corpo Permanente. Acquisisci le competenze!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frontexprep.com\/it\/","og_locale":"it_IT","og_type":"article","og_title":"FrontexPrep &#8226; Corso per Candidati al Corpo Permanente di Frontex","og_description":"Prepara per il reclutamento Frontex con il nostro corso progettato per i candidati al Corpo Permanente. Acquisisci le competenze!","og_url":"https:\/\/frontexprep.com\/it\/","og_site_name":"FrontexPrep","article_modified_time":"2025-04-25T16:37:20+00:00","og_image":[{"width":48,"height":123,"url":"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/h-1-shape-01.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frontexprep.com\/it\/","url":"https:\/\/frontexprep.com\/it\/","name":"FrontexPrep &#8226; Corso per Candidati al Corpo Permanente di Frontex","isPartOf":{"@id":"https:\/\/frontexprep.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frontexprep.com\/it\/#primaryimage"},"image":{"@id":"https:\/\/frontexprep.com\/it\/#primaryimage"},"thumbnailUrl":"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/h-1-shape-01.png","datePublished":"2023-05-18T13:46:17+00:00","dateModified":"2025-04-25T16:37:20+00:00","description":"Prepara per il reclutamento Frontex con il nostro corso progettato per i candidati al Corpo Permanente. Acquisisci le competenze!","breadcrumb":{"@id":"https:\/\/frontexprep.com\/it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frontexprep.com\/it\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/frontexprep.com\/it\/#primaryimage","url":"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/h-1-shape-01.png","contentUrl":"https:\/\/frontexprep.com\/wp-content\/uploads\/2023\/05\/h-1-shape-01.png"},{"@type":"BreadcrumbList","@id":"https:\/\/frontexprep.com\/it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frontexprep.com\/it\/"},{"@type":"ListItem","position":2,"name":"Corso per Candidati al Corpo Permanente di Frontex"}]},{"@type":"WebSite","@id":"https:\/\/frontexprep.com\/it\/#website","url":"https:\/\/frontexprep.com\/it\/","name":"FrontexPrep","description":"Course on Frontex Standing Corps Recruitment","publisher":{"@id":"https:\/\/frontexprep.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frontexprep.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/frontexprep.com\/it\/#organization","name":"FrontexPrep","url":"https:\/\/frontexprep.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/frontexprep.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Standing-Corps-prep-course-logo.png","contentUrl":"https:\/\/frontexprep.com\/wp-content\/uploads\/2025\/01\/Standing-Corps-prep-course-logo.png","width":158,"height":50,"caption":"FrontexPrep"},"image":{"@id":"https:\/\/frontexprep.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/pages\/30352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/comments?post=30352"}],"version-history":[{"count":41,"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/pages\/30352\/revisions"}],"predecessor-version":[{"id":34695,"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/pages\/30352\/revisions\/34695"}],"wp:attachment":[{"href":"https:\/\/frontexprep.com\/it\/wp-json\/wp\/v2\/media?parent=30352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}